{"id":29508,"date":"2024-08-22T09:59:26","date_gmt":"2024-08-22T09:59:26","guid":{"rendered":"https:\/\/sustain-ed.eu\/?page_id=29508"},"modified":"2025-04-04T08:54:40","modified_gmt":"2025-04-04T08:54:40","slug":"sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado","status":"publish","type":"page","link":"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/","title":{"rendered":"Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"29508\" class=\"elementor elementor-29508 elementor-22009\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f47f196 e-flex e-con-boxed sc_layouts_column_icons_position_left wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"f47f196\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fce31d7 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"fce31d7\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_accent\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_item_subtitle_above sc_item_title_style_accent sc_item_subtitle_with_custom_color trx_addons_inline_33371032\">Tem\u00e1tica de la webquest: Sostenibilidad y ESG<\/span><h2 class=\"sc_item_title sc_title_title sc_item_title_style_accent\"\n\t\t\t><span class=\"sc_item_title_text\">Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89e1ed6 e-flex e-con-boxed sc_layouts_column_icons_position_left wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"89e1ed6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fde0d37 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"fde0d37\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sustain-ed.eu\/wp-content\/uploads\/elementor\/thumbs\/wq4-2-1-qt0pimrymz6uzn8plrtumszkkms9nm22s4fk90cyyo.webp\" title=\"wq4-2-1\" alt=\"wq4-2-1\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6af3f28 wpr-feature-list-left wpr-feature-list-square wpr-feature-list-line-yes sc_fly_static elementor-widget elementor-widget-wpr-feature-list\" data-id=\"6af3f28\" data-element_type=\"widget\" data-widget_type=\"wpr-feature-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpr-feature-list-wrap\"><ul class=\"wpr-feature-list\"><li class=\"wpr-feature-list-item elementor-repeater-item-a430942\"><div class=\"wpr-feature-list-icon-wrap\"><span class=\"wpr-feature-list-line\"><\/span><div class=\"wpr-feature-list-icon-inner-wrap\"><i aria-hidden=\"true\" class=\"fas fa-book-open\"><\/i><\/div><\/div><div class=\"wpr-feature-list-content-wrap\"><h2 class=\"wpr-feature-list-title\"><a class=\"wpr-feature-list-url\" target=\"_blank\" rel=\"nofollow\">Conocimientos<\/a><\/h2><p class=\"wpr-feature-list-description\"><ul style=\"list-style-type: square\">\n<li style=\"font-size: 0.8em;line-height: 1.5\">Conocimientos avanzados de an\u00e1lisis de ciclo de vida (ACV), cadena de suministros de circuito cerrado y t\u00e9cnicas de evaluaci\u00f3n de impacto ambiental.<\/li>\n<li style=\"font-size: 0.8em;line-height: 1.5\">Comprensi\u00f3n cr\u00edtica de las teor\u00edas y principios relacionados con la sostenibilidad y la econom\u00eda circular.<\/li>\n<\/ul><\/p><\/div><\/li><li class=\"wpr-feature-list-item elementor-repeater-item-0a26ef8\"><div class=\"wpr-feature-list-icon-wrap\"><span class=\"wpr-feature-list-line\"><\/span><div class=\"wpr-feature-list-icon-inner-wrap\"><i aria-hidden=\"true\" class=\"fas fa-brain\"><\/i><\/div><\/div><div class=\"wpr-feature-list-content-wrap\"><h2 class=\"wpr-feature-list-title\"><a class=\"wpr-feature-list-url\" target=\"_blank\" rel=\"nofollow\">Competencias<\/a><\/h2><p class=\"wpr-feature-list-description\"><ul style=\"list-style-type: square\">\n<li style=\"font-size: 0.8em;line-height: 1.5\">Habilidades avanzadas para realizar un an\u00e1lisis de ciclo de vida, identificar puntos cr\u00edticos y proponer mejoras.<\/li>\n<li style=\"font-size: 0.8em;line-height: 1.5\">Competencias innovadoras para dise\u00f1ar e implementar estrategias de cadena de suministro de circuito cerrado.<\/li>\n<li style=\"font-size: 0.8em;line-height: 1.5\">Competencia en el uso de herramientas y m\u00e9todos para la evaluaci\u00f3n de impacto ambiental.<\/li>\n<\/ul><\/p><\/div><\/li><li class=\"wpr-feature-list-item elementor-repeater-item-269dcd1\"><div class=\"wpr-feature-list-icon-wrap\"><span class=\"wpr-feature-list-line\"><\/span><div class=\"wpr-feature-list-icon-inner-wrap\"><i aria-hidden=\"true\" class=\"fas fa-burn\"><\/i><\/div><\/div><div class=\"wpr-feature-list-content-wrap\"><h2 class=\"wpr-feature-list-title\"><a class=\"wpr-feature-list-url\" target=\"_blank\" rel=\"nofollow\">Responsabilidad y autonom\u00eda<\/a><\/h2><p class=\"wpr-feature-list-description\"><ul style=\"list-style-type: square\">\n<li style=\"font-size: 0.8em;line-height: 1.5\">Identificar de manera aut\u00f3noma oportunidades y dise\u00f1ar estrategias para la implementaci\u00f3n de cadenas de suministro de circuito cerrado.<\/li>\n<li style=\"font-size: 0.8em;line-height: 1.5\">Promover un mayor nivel de comprensi\u00f3n sobre los temas de evaluaci\u00f3n del ciclo de vida y cadenas de suministro de circuito cerrado, entre otros.<\/li>\n<\/ul><\/p><\/div><\/li><\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4859a9a e-flex e-con-boxed sc_layouts_column_icons_position_left wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"4859a9a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6670c5c e-con-full e-flex sc_layouts_column_icons_position_left wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"6670c5c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4a1b5f elementor-widget__width-initial wpr-advanced-accordion-icon-side-box sc_fly_static elementor-widget elementor-widget-wpr-advanced-accordion\" data-id=\"b4a1b5f\" data-element_type=\"widget\" data-settings=\"{&quot;active_item&quot;:1}\" data-widget_type=\"wpr-advanced-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"wpr-advanced-accordion\" data-accordion-type=\"accordion\" data-active-index=\"1\" data-accordion-trigger=\"click\" data-interaction-speed=\"0.4\">\n\n\t\t\t\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-bookmark\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">INTRODUCCI\u00d3N<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>La sostenibilidad ambiental se ha convertido en una prioridad para las empresas de todo el mundo, impulsada por una mayor conciencia sobre el cambio clim\u00e1tico, el agotamiento de los recursos y la degradaci\u00f3n ambiental. Las empresas se encuentran ahora bajo una presi\u00f3n significativa para reducir su huella ambiental y adoptar pr\u00e1cticas sostenibles. En este WebQuest, nos sumergiremos en un escenario espec\u00edfico para comprender y abordar mejor estos desaf\u00edos.<\/p><p>Imagina que formas parte del equipo de desarrollo de productos de una reconocida empresa que fabrica refrigeradores dom\u00e9sticos. La compa\u00f1\u00eda est\u00e1 comprometida con el lanzamiento de un nuevo modelo que no solo satisfaga las demandas de los consumidores en cuanto a eficiencia y funcionalidad, sino que tambi\u00e9n se alinee con los m\u00e1s altos est\u00e1ndares de sostenibilidad ambiental. A su equipo se le ha encomendado la tarea de un proyecto integral que incluye la realizaci\u00f3n de un an\u00e1lisis del ciclo de vida (LCA), el desarrollo de una estrategia de cadena de suministro de circuito cerrado y la realizaci\u00f3n de una evaluaci\u00f3n de impacto para el nuevo modelo de refrigerador.<\/p><p>El an\u00e1lisis del ciclo de vida (ACV) es una herramienta fundamental que eval\u00faa los impactos ambientales asociados a todas las etapas de la vida de un producto. Esto incluye la extracci\u00f3n, fabricaci\u00f3n, distribuci\u00f3n, uso y eliminaci\u00f3n de materias primas. Al realizar un ACV, su equipo obtendr\u00e1 informaci\u00f3n valiosa sobre la huella ambiental del producto. Este proceso implica identificar los puntos cr\u00edticos donde el producto tiene los impactos ambientales m\u00e1s significativos y explorar oportunidades de mejora. Por ejemplo, analizando el consumo de energ\u00eda durante la fase de uso o la reciclabilidad de los materiales utilizados, se pueden proponer modificaciones que hagan que el frigor\u00edfico sea m\u00e1s sostenible.<\/p><p>Una estrategia de cadena de suministro de circuito cerrado se centra en la creaci\u00f3n de un sistema en el que los productos al final de su vida \u00fatil se reciclen o reutilicen, reduciendo as\u00ed los residuos y minimizando la necesidad de nuevas materias primas. Su tarea consistir\u00e1 en desarrollar una estrategia que integre componentes reciclados en el proceso de producci\u00f3n del nuevo refrigerador. Esto puede incluir el dise\u00f1o para el desmontaje para facilitar el reciclaje o la selecci\u00f3n de materiales que sean m\u00e1s sostenibles y tengan un menor impacto ambiental. La implementaci\u00f3n de una estrategia de este tipo no solo ayuda a reducir los residuos, sino que tambi\u00e9n promueve una econom\u00eda circular, que es esencial para la sostenibilidad a largo plazo. La evaluaci\u00f3n de impacto es otro aspecto crucial de su proyecto. Se trata de medir y analizar las consecuencias medioambientales de las estrategias que propones. Esto incluye cuantificar la reducci\u00f3n de la huella de carbono lograda a trav\u00e9s de las mejoras del ACV y los beneficios de la estrategia de cadena de suministro de circuito cerrado. Se utilizar\u00e1n herramientas como calculadoras de carbono, software de evaluaci\u00f3n de impacto ambiental y m\u00e9tricas de sostenibilidad para evaluar la eficacia general de las soluciones propuestas. Esta evaluaci\u00f3n ayudar\u00e1 a su equipo a comprender los beneficios tangibles de sus estrategias y proporcionar\u00e1 un camino claro para que la empresa siga en sus esfuerzos de sostenibilidad.<\/p><p>A lo largo de este WebQuest, participar\u00e1 en una experiencia de aprendizaje pr\u00e1ctica e inmersiva. Al aplicar estos conceptos a un escenario del mundo real, no solo comprender\u00e1 los fundamentos te\u00f3ricos de la sostenibilidad, sino que tambi\u00e9n obtendr\u00e1 experiencia pr\u00e1ctica en la implementaci\u00f3n de pr\u00e1cticas sostenibles. Llevar\u00e1 a cabo un an\u00e1lisis detallado del ciclo de vida del nuevo modelo de refrigerador, desarrollar\u00e1 estrategias innovadoras para una cadena de suministro de circuito cerrado y evaluar\u00e1 rigurosamente los impactos ambientales de las soluciones propuestas. Al imaginarte a ti mismo como parte de un equipo de desarrollo de productos, obtendr\u00e1s conocimientos pr\u00e1cticos y desarrollar\u00e1s la experiencia necesaria para impulsar la innovaci\u00f3n sostenible en tu futura carrera. Sus contribuciones a este proyecto, por peque\u00f1as que sean, allanar\u00e1n el camino para cambios positivos significativos para el medio ambiente, ayudando a crear un mundo mejor para las generaciones futuras.<\/p><p>\u00a1Buena suerte!<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">TAREA<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>Como parte de esta WebQuest, tu equipo tendr\u00e1 las siguientes tareas:<\/p><ul style=\"list-style-type: square;\"><li>Realizar un an\u00e1lisis del ciclo de vida (ACV) de un modelo espec\u00edfico de refrigerador.<\/li><li>Desarrollar una estrategia de cadena de suministro de circuito cerrado para el producto, identificando formas de reducir el desperdicio y reciclar materiales.<\/li><li>Evaluar el impacto ambiental de la estrategia propuesta utilizando herramientas y m\u00e9todos espec\u00edficos.<\/li><li>Recopile los resultados en un informe detallado.<\/li><li>Prepare una presentaci\u00f3n multimedia para compartir los hallazgos con la clase.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bezier-curve\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">PROCESO<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>En este WebQuest, seguir\u00e1 un proceso estructurado para completar su proyecto como parte del equipo de desarrollo de productos de una empresa de fabricaci\u00f3n de refrigeradores. Este proceso est\u00e1 dise\u00f1ado para ayudarlo a realizar sistem\u00e1ticamente un an\u00e1lisis del ciclo de vida (LCA), desarrollar una estrategia de cadena de suministro de circuito cerrado y realizar una evaluaci\u00f3n de impacto para el nuevo modelo de refrigerador. Adem\u00e1s, participar\u00e1 en un entorno de laboratorio viviente, interactuar\u00e1 con las partes interesadas y crear\u00e1 prototipos de sus soluciones para garantizar la aplicaci\u00f3n pr\u00e1ctica y la relevancia en el mundo real.<\/p><p>Proceso paso a paso:<\/p><ol><li><strong>Formaci\u00f3n de grupos:<\/strong> Dividir la clase en grupos de 3-4 estudiantes. Cada grupo actuar\u00e1 como un equipo de desarrollo de producto responsable de mejorar la sostenibilidad de un nuevo modelo de refrigerador.<\/li><li><strong>Selecci\u00f3n de productos e investigaci\u00f3n inicial:<\/strong> Comience seleccionando un modelo de refrigerador espec\u00edfico para su an\u00e1lisis. Realizar una investigaci\u00f3n inicial para comprender el dise\u00f1o actual, los materiales utilizados y las etapas del ciclo de vida del producto. Utilice los recursos proporcionados en los WebQues, as\u00ed como los informes de la empresa, los art\u00edculos acad\u00e9micos y las publicaciones de la industria.<\/li><li><strong>An\u00e1lisis del ciclo de vida (ACV) - actividad de laboratorio viviente:<\/strong> Realice un ACV completo para el modelo de refrigerador seleccionado. Utilice herramientas gratuitas como <a href=\"https:\/\/www.openlca.org\/\">OpenLCA<\/a> para evaluar los impactos ambientales en todas las etapas del ciclo de vida del producto. Siga estos pasos:<br \/><ul style=\"list-style-type: square;\"><li>Definir el objetivo y el alcance del ACV.<\/li><li>Realizar un an\u00e1lisis de inventario de los datos de entrada y salida.<\/li><li>Realizar una evaluaci\u00f3n de impacto.<\/li><li>Interpretar los resultados e identificar los puntos cr\u00edticos donde el impacto ambiental es mayor.<\/li><\/ul><p>Para obtener informaci\u00f3n valiosa de la industria y llevar a cabo su ACV, identifique e interact\u00fae con las partes interesadas clave, incluidos proveedores, fabricantes, consumidores y expertos ambientales. Organice reuniones o entrevistas virtuales para recopilar informaci\u00f3n sobre el ciclo de vida (de la cuna a la tumba) del refrigerador.<\/p><\/li><li><strong>Estrategia de cadena de suministro de circuito cerrado:<\/strong> Desarrollar una estrategia para incorporar materiales reciclados y dise\u00f1o para el desmontaje en el proceso de producci\u00f3n de refrigeradores. Considere formas de reintroducir productos al final de su vida \u00fatil en la cadena de suministro. Cree un plan detallado que describa los pasos necesarios para implementar esta estrategia, incluidos los cambios necesarios en los procesos de dise\u00f1o, abastecimiento y fabricaci\u00f3n.<\/li><li><strong>Evaluaci\u00f3n de impacto:<\/strong> Utilice herramientas de evaluaci\u00f3n de impacto ambiental, como <a href=\"https:\/\/www.openlca.org\/\">OpenLCA<\/a>, para medir los beneficios de las mejoras propuestas. Cuantifique la reducci\u00f3n de la huella de carbono, el uso de energ\u00eda y el desperdicio de materiales lograda a trav\u00e9s de su estrategia de ACV y cadena de suministro de circuito cerrado. Compare estos resultados con los datos de referencia iniciales.<\/li><li><strong>Creaci\u00f3n de prototipos de actividades de laboratorio viviente (opcional):<\/strong><br \/><ul style=\"list-style-type: square;\"><li><strong>Descripci\u00f3n de la actividad:<\/strong> Crear un prototipo o modelo del dise\u00f1o mejorado del refrigerador utilizando materiales y m\u00e9todos sostenibles. Esta actividad es opcional y se puede adaptar en funci\u00f3n de los recursos disponibles.<\/li><li><strong>M\u00e9todos sostenibles de creaci\u00f3n de prototipos:<\/strong><br \/><ul style=\"list-style-type: circle;\"><li><strong>Modelado digital:<\/strong> Utilice herramientas gratuitas de modelado 3D como <a href=\"https:\/\/www.tinkercad.com\/\">Tinkercad<\/a> para crear un modelo digital del refrigerador mejorado. <a href=\"https:\/\/www.tinkercad.com\/\">Esta herramienta<\/a> es accesible en l\u00ednea y f\u00e1cil de usar para principiantes.<\/li><li><strong>Prototipado con materiales reciclados:<\/strong><br \/><ul style=\"list-style-type: circle;\"><li>Utilice materiales reciclados y f\u00e1cilmente disponibles para construir un modelo f\u00edsico. Por ejemplo, el cart\u00f3n, el pl\u00e1stico reciclado y otros materiales reutilizados se pueden utilizar para representar diferentes partes del refrigerador.<\/li><li>Haz una lista de los materiales que puedes reciclar y usa tu creatividad para armar el prototipo.<\/li><\/ul><\/li><li><strong>Prototipado r\u00e1pido con papel y pegamento:<\/strong> Si no tienes acceso a herramientas digitales o materiales espec\u00edficos, puedes crear un modelo sencillo con papel, pegamento y colores. Dibuja las distintas partes del refrigerador en papel, rec\u00f3rtalas y m\u00f3ntalas para crear un modelo tridimensional.<\/li><\/ul><p>El prototipo debe mostrar c\u00f3mo el dise\u00f1o mejorado incorpora materiales reciclados y c\u00f3mo el refrigerador puede desmontarse f\u00e1cilmente para su reciclaje al final de su vida \u00fatil.<\/p><\/li><li><strong>Descripci\u00f3n del proyecto:<\/strong> Escriba una breve descripci\u00f3n del prototipo, explicando las opciones de dise\u00f1o sostenible y c\u00f3mo contribuyen a reducir el impacto ambiental.<\/li><\/ul><\/li><li><strong>Presenta tu proyecto: Haz una presentaci\u00f3n multimedia que contenga lo siguiente:<\/strong><br \/><ul style=\"list-style-type: square;\"><li><strong>Introducci\u00f3n:<\/strong> Proporcionar una visi\u00f3n general del proyecto y explicar la importancia de la sostenibilidad para el nuevo modelo de refrigerador.<\/li><li><strong>Perspectivas de los grupos de inter\u00e9s y hallazgos clave:<\/strong> Resuma los conocimientos recopilados de las interacciones con los grupos de inter\u00e9s y los principales resultados del An\u00e1lisis del Ciclo de Vida (ACV). Incluya gr\u00e1ficos y datos para respaldar sus hallazgos.<\/li><li><strong>Evaluaci\u00f3n de impacto y creaci\u00f3n de prototipos:<\/strong> Describa la evaluaci\u00f3n de impacto, si\u00e9ntase libre de utilizar im\u00e1genes generadas por IA o modeladas en 3D de su nuevo refrigerador sostenible mejorado en caso de que haya implementado las actividades opcionales. Explique c\u00f3mo los comentarios de las partes interesadas y el an\u00e1lisis del ACV influyeron en el dise\u00f1o final y por qu\u00e9 es sostenible.<\/li><li>Describa por escrito o con un diagrama la cadena de suministro de circuito cerrado para su refrigerador.<\/li><li><strong>Conclusi\u00f3n:<\/strong> Resuma los beneficios medioambientales de sus estrategias y reflexione sobre las competencias adquiridas y su relevancia para futuras iniciativas de sostenibilidad. Invite a la audiencia a hacer preguntas y discutir.<\/li><\/ul><\/li><li>Presente su trabajo a la clase, explicando sus hallazgos y las mejoras propuestas. Destaca las aplicaciones pr\u00e1cticas de tus estrategias y los beneficios de tu nuevo frigor\u00edfico sostenible. Interact\u00fae con su audiencia respondiendo preguntas y discutiendo posibles desarrollos futuros.<\/li><\/ol><p>Al seguir este proceso, obtendr\u00e1 una comprensi\u00f3n profunda de las complejidades involucradas en hacer que los productos sean m\u00e1s sostenibles. Tambi\u00e9n desarrollar\u00e1 habilidades pr\u00e1cticas en la realizaci\u00f3n de ACV, el dise\u00f1o de cadenas de suministro de circuito cerrado y la interacci\u00f3n con las partes interesadas como parte de las actividades de laboratorio viviente en este WebQuest.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-list-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">RECURSOS<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>En esta WebQuest, necesitar\u00e1 varios recursos que le ayuden a comprender y aplicar los conceptos de An\u00e1lisis de Ciclo de Vida (ACV), Cadenas de Suministro de Circuito Cerrado y Evaluaci\u00f3n de Impacto. Los siguientes enlaces y herramientas le proporcionar\u00e1n el conocimiento y el apoyo necesarios para completar su proyecto y presentaci\u00f3n con \u00e9xito.<\/p><ul style=\"list-style-type: square;\"><li>An\u00e1lisis de ciclo de vida (ACV):<ul><li><a href=\"https:\/\/www.researchgate.net\/publication\/260041338_Life_Cycle_Assessment_of_a_commercial_refrigeration_system_under_different_use_configurations\">(PDF) Life Cycle Assessment of a commercial refrigeration system under different use configurations<\/a><\/li><li><a href=\"https:\/\/www.mdpi.com\/1996-1073\/14\/17\/5350\">Environmental Life Cycle Assessment of Refrigerator Modelled with Application of Various Electricity Mixes and Technologies<\/a><\/li><li><a href=\"https:\/\/ecochain.com\/blog\/life-cycle-assessment-lca-guide\/\">Life Cycle Assessment (LCA) \u2013 Everything you need to know | Ecochain<\/a><\/li><li><a href=\"https:\/\/www.rit.edu\/sustainabilityinstitute\/blog\/what-life-cycle-assessment-lca\">What is life cycle assessment (LCA)? | Golisano Institute for Sustainability | RIT<\/a><\/li><li><a href=\"https:\/\/www.openlca.org\/\">OpenLCA<\/a>: Herramienta para evaluar los impactos ambientales en todas las etapas del ciclo de vida del producto.<\/li><li><a href=\"https:\/\/www.openlca.org\/learning\/\">Learning | openLCA.org:<\/a> contiene gu\u00edas detalladas sobre c\u00f3mo usar OpenLCA, incluidos los conceptos b\u00e1sicos de instalaci\u00f3n y el uso de funciones clave.<\/li><\/ul><\/li><li>Cadenas de suministro de circuito cerrado<ul><li><a href=\"https:\/\/aims.education\/closed-loop-supply-chain-management\/\">Closed Loop Supply Chain (CLSC): Meaning &amp; Examples<\/a><\/li><li><a href=\"https:\/\/sites.insead.edu\/facultyresearch\/research\/doc.cfm?did=19631\">The Evolution of Closed Loop Supply Chains (research paper)<\/a><\/li><\/ul><\/li><li>M\u00e9todo de creaci\u00f3n de prototipos<ul><li><a href=\"https:\/\/www.tinkercad.com\/\">Tinkercad<\/a>: es una herramienta en l\u00ednea accesible para la creaci\u00f3n de prototipos 3D que es f\u00e1cil de usar para principiantes.<\/li><li><a href=\"https:\/\/www.tinkercad.com\/learn\">Learn how to use Tinkercad<\/a>: un recurso completo con tutoriales y lecciones para aprender a usar Tinkercad, incluidos proyectos paso a paso.<\/li><li><a href=\"https:\/\/www.freepik.com\/pikaso\/ai-image-generator\">FreePik AI image generator<\/a><\/li><\/ul><\/li><li>Evaluaci\u00f3n de impacto:<ul><li><a href=\"https:\/\/www.footprintcalculator.org\/home\/en\">Carbon footprint calculators<\/a>: Herramientas para medir la huella de carbono de productos y actividades.<\/li><li><a href=\"https:\/\/twin40.eu\/twin-4-0-environmental-impact-audit-tool\/\">TWIN 4.0 Environmental impact calculation tools<\/a><\/li><\/ul><\/li><li>Recursos generales de sostenibilidad:<ul><li><a href=\"https:\/\/www.sustainability101.in\/\">Sustainability 101<\/a>: Conceptos y principios b\u00e1sicos de la sostenibilidad.<\/li><\/ul><\/li><\/ul><p>Estos recursos te ayudar\u00e1n a construir una s\u00f3lida comprensi\u00f3n de los conceptos clave necesarios para tu proyecto. Util\u00edcelos para recopilar informaci\u00f3n, respaldar sus an\u00e1lisis y mejorar sus presentaciones.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-comment-dots\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">CONCLUSI\u00d3N<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>La sostenibilidad no es solo una palabra de moda, sino un compromiso concreto con el futuro de nuestro planeta. A lo largo de esta WebQuest, ha profundizado en las complejidades del an\u00e1lisis del ciclo de vida, las cadenas de suministro de circuito cerrado y la evaluaci\u00f3n del impacto ambiental. Estos conceptos no son solo te\u00f3ricos, sino que tienen aplicaciones pr\u00e1cticas que pueden reducir significativamente la huella ambiental de productos y procesos.<\/p><p>Al realizar un an\u00e1lisis del ciclo de vida, ha identificado los puntos cr\u00edticos en la vida \u00fatil del producto en los que se pueden realizar mejoras. El desarrollo de una estrategia de cadena de suministro de circuito cerrado le ha demostrado la importancia de reutilizar y reciclar materiales, reducir la necesidad de recursos brutos y minimizar los residuos. La evaluaci\u00f3n de impacto ha proporcionado una imagen clara de c\u00f3mo estas estrategias benefician al medio ambiente, ofreciendo un camino hacia pr\u00e1cticas m\u00e1s sostenibles.<\/p><p>Reflexiona sobre los conocimientos y habilidades que has adquirido durante este proyecto. Estas herramientas te permiten tomar decisiones informadas e implementar pr\u00e1cticas sostenibles en tus futuras carreras y en tu vida diaria. Sus contribuciones, por peque\u00f1as que sean, pueden conducir a cambios positivos significativos para el medio ambiente. Contin\u00faa explorando y abogando por la sostenibilidad, y ayudar\u00e1s a crear un mundo mejor para las generaciones futuras.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-newspaper\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">RECURSOS ADICIONALES<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><ul style=\"list-style-type: square;\"><li><a href=\"https:\/\/www.dbooks.org\/life-cycle-assessment-3319564757\/#google_vignette\">An\u00e1lisis de Ciclo de Vida (ACV) (Este libro ofrece una descripci\u00f3n pedag\u00f3gica y completa de la metodolog\u00eda del ACV, cubriendo la historia, el contexto, la metodolog\u00eda y una amplia gama de aplicaciones. Est\u00e1 disponible en formato PDF.)<\/a><\/li><li><a href=\"https:\/\/archive.org\/details\/lifecycleassessm0000simo\">An\u00e1lisis de Ciclo de Vida (Este libro proporciona una visi\u00f3n detallada del An\u00e1lisis del Ciclo de Vida, con especial atenci\u00f3n a los aspectos medioambientales de los edificios y los materiales de construcci\u00f3n.)<\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-handshake\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">BUENAS PR\u00c1CTICAS<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p><strong>Iniciativa de Econom\u00eda Circular de Philips<\/strong><\/p><p>Philips ha implementado un modelo de econom\u00eda circular en sus productos electr\u00f3nicos, centr\u00e1ndose en la reducci\u00f3n de residuos y la eficiencia de los materiales. A trav\u00e9s del dise\u00f1o para la reciclabilidad y la reutilizaci\u00f3n, Philips ha reducido significativamente su impacto ambiental. Este ejemplo ilustra c\u00f3mo las empresas pueden adoptar pr\u00e1cticas sostenibles para mejorar la eficiencia y reducir los costes, al tiempo que protegen el medio ambiente.<\/p><p>Enlace: <a href=\"https:\/\/www.philips.com\/a-w\/about\/environmental-social-governance\/environmental\/circular-economy.html\">The circular imperative<\/a><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                            <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-350e70a e-con-full e-flex sc_layouts_column_icons_position_left wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"350e70a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f65ef1a sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"6f65ef1a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Todas las WebQuests<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c29a48d wpr-feature-list-left wpr-feature-list-square wpr-feature-list-line-yes sc_fly_static elementor-widget elementor-widget-wpr-feature-list\" data-id=\"3c29a48d\" data-element_type=\"widget\" data-widget_type=\"wpr-feature-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpr-feature-list-wrap\"><ul class=\"wpr-feature-list\"><li class=\"wpr-feature-list-item elementor-repeater-item-3d0b4cb\"><div class=\"wpr-feature-list-icon-wrap\"><span class=\"wpr-feature-list-line\"><\/span><div class=\"wpr-feature-list-icon-inner-wrap\"><i aria-hidden=\"true\" class=\"fas fa-stream\"><\/i><\/div><\/div><div class=\"wpr-feature-list-content-wrap\"><h4 class=\"wpr-feature-list-title\"><a class=\"wpr-feature-list-url\" href=\"https:\/\/sustain-ed.eu\/es\/sustainedx-conjunto-de-herramientas-de-aprendizaje-sostenible-para-estudiantes-de-educacion-superior\/#topic1\" target=\"_blank\" rel=\"nofollow\">Tema: Sostenibilidad y ESG<\/a><\/h4><p class=\"wpr-feature-list-description\"><\/p><\/div><\/li><li class=\"wpr-feature-list-item elementor-repeater-item-04d6f30\"><div class=\"wpr-feature-list-icon-wrap\"><span class=\"wpr-feature-list-line\"><\/span><div class=\"wpr-feature-list-icon-inner-wrap\"><i aria-hidden=\"true\" class=\"fas fa-exchange-alt\"><\/i><\/div><\/div><div class=\"wpr-feature-list-content-wrap\"><h4 class=\"wpr-feature-list-title\"><a class=\"wpr-feature-list-url\" href=\"https:\/\/sustain-ed.eu\/es\/sustainedx-conjunto-de-herramientas-de-aprendizaje-sostenible-para-estudiantes-de-educacion-superior\/#topic2\" target=\"_blank\" rel=\"nofollow\">Tema: Gesti\u00f3n sostenible de la cadena de suministro<\/a><\/h4><p class=\"wpr-feature-list-description\"><\/p><\/div><\/li><li class=\"wpr-feature-list-item elementor-repeater-item-cfa533f\"><div class=\"wpr-feature-list-icon-wrap\"><span class=\"wpr-feature-list-line\"><\/span><div class=\"wpr-feature-list-icon-inner-wrap\"><i aria-hidden=\"true\" class=\"fas fa-coins\"><\/i><\/div><\/div><div class=\"wpr-feature-list-content-wrap\"><h4 class=\"wpr-feature-list-title\"><a class=\"wpr-feature-list-url\" href=\"https:\/\/sustain-ed.eu\/es\/sustainedx-conjunto-de-herramientas-de-aprendizaje-sostenible-para-estudiantes-de-educacion-superior\/#topic3\" target=\"_blank\" rel=\"nofollow\">Tema: Finanzas sostenibles<\/a><\/h4><p class=\"wpr-feature-list-description\"><\/p><\/div><\/li><li class=\"wpr-feature-list-item elementor-repeater-item-69706e5\"><div class=\"wpr-feature-list-icon-wrap\"><span class=\"wpr-feature-list-line\"><\/span><div class=\"wpr-feature-list-icon-inner-wrap\"><i aria-hidden=\"true\" class=\"fas fa-briefcase\"><\/i><\/div><\/div><div class=\"wpr-feature-list-content-wrap\"><h4 class=\"wpr-feature-list-title\"><a class=\"wpr-feature-list-url\" href=\"https:\/\/sustain-ed.eu\/es\/sustainedx-conjunto-de-herramientas-de-aprendizaje-sostenible-para-estudiantes-de-educacion-superior\/#topic4\" target=\"_blank\" rel=\"nofollow\">Tema: Modelos de negocio de economia circular<\/a><\/h4><p class=\"wpr-feature-list-description\"><\/p><\/div><\/li><\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tem\u00e1tica de la webquest: Sostenibilidad y ESG Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado Conocimientos Conocimientos avanzados de an\u00e1lisis de ciclo de&hellip;<\/p>\n","protected":false},"author":5,"featured_media":22040,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-29508","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado | SustainEd<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado | SustainEd\" \/>\n<meta property=\"og:description\" content=\"Tem\u00e1tica de la webquest: Sostenibilidad y ESG Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado Conocimientos Conocimientos avanzados de an\u00e1lisis de ciclo de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/\" \/>\n<meta property=\"og:site_name\" content=\"SustainEd\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/projectSustainEd\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-04T08:54:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sustain-ed.eu\/wp-content\/uploads\/2024\/08\/wq4-2-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"567\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/es\\\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\\\/\",\"url\":\"https:\\\/\\\/sustain-ed.eu\\\/es\\\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\\\/\",\"name\":\"Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado | SustainEd\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/es\\\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/es\\\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sustain-ed.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/wq4-2-1.webp\",\"datePublished\":\"2024-08-22T09:59:26+00:00\",\"dateModified\":\"2025-04-04T08:54:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/es\\\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sustain-ed.eu\\\/es\\\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/es\\\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sustain-ed.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/wq4-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/sustain-ed.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/wq4-2-1.webp\",\"width\":567,\"height\":567},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/es\\\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sustain-ed.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/#website\",\"url\":\"https:\\\/\\\/sustain-ed.eu\\\/\",\"name\":\"SustainEd\",\"description\":\"SustainEd Erasmus+ Project\",\"publisher\":{\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sustain-ed.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/#organization\",\"name\":\"SustainEd\",\"url\":\"https:\\\/\\\/sustain-ed.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sustain-ed.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/SustainEd_Logo.png\",\"contentUrl\":\"https:\\\/\\\/sustain-ed.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/SustainEd_Logo.png\",\"width\":300,\"height\":300,\"caption\":\"SustainEd\"},\"image\":{\"@id\":\"https:\\\/\\\/sustain-ed.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/projectSustainEd\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/102452710\",\"https:\\\/\\\/www.youtube.com\\\/@SustainEdProject\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado | SustainEd","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/","og_locale":"es_ES","og_type":"article","og_title":"Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado | SustainEd","og_description":"Tem\u00e1tica de la webquest: Sostenibilidad y ESG Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado Conocimientos Conocimientos avanzados de an\u00e1lisis de ciclo de&hellip;","og_url":"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/","og_site_name":"SustainEd","article_publisher":"https:\/\/www.facebook.com\/projectSustainEd","article_modified_time":"2025-04-04T08:54:40+00:00","og_image":[{"width":567,"height":567,"url":"https:\/\/sustain-ed.eu\/wp-content\/uploads\/2024\/08\/wq4-2-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/","url":"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/","name":"Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado | SustainEd","isPartOf":{"@id":"https:\/\/sustain-ed.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/#primaryimage"},"image":{"@id":"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/#primaryimage"},"thumbnailUrl":"https:\/\/sustain-ed.eu\/wp-content\/uploads\/2024\/08\/wq4-2-1.webp","datePublished":"2024-08-22T09:59:26+00:00","dateModified":"2025-04-04T08:54:40+00:00","breadcrumb":{"@id":"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/#primaryimage","url":"https:\/\/sustain-ed.eu\/wp-content\/uploads\/2024\/08\/wq4-2-1.webp","contentUrl":"https:\/\/sustain-ed.eu\/wp-content\/uploads\/2024\/08\/wq4-2-1.webp","width":567,"height":567},{"@type":"BreadcrumbList","@id":"https:\/\/sustain-ed.eu\/es\/sostenibilidad-en-accion-analisis-del-ciclo-de-vida-y-cadenas-de-suministro-de-circuito-cerrado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sustain-ed.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Sostenibilidad en Acci\u00f3n: An\u00e1lisis del Ciclo de Vida y Cadenas de Suministro de Circuito Cerrado"}]},{"@type":"WebSite","@id":"https:\/\/sustain-ed.eu\/#website","url":"https:\/\/sustain-ed.eu\/","name":"SustainEd","description":"SustainEd Erasmus+ Project","publisher":{"@id":"https:\/\/sustain-ed.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sustain-ed.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sustain-ed.eu\/#organization","name":"SustainEd","url":"https:\/\/sustain-ed.eu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sustain-ed.eu\/#\/schema\/logo\/image\/","url":"https:\/\/sustain-ed.eu\/wp-content\/uploads\/2024\/06\/SustainEd_Logo.png","contentUrl":"https:\/\/sustain-ed.eu\/wp-content\/uploads\/2024\/06\/SustainEd_Logo.png","width":300,"height":300,"caption":"SustainEd"},"image":{"@id":"https:\/\/sustain-ed.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/projectSustainEd","https:\/\/www.linkedin.com\/company\/102452710","https:\/\/www.youtube.com\/@SustainEdProject"]}]}},"_links":{"self":[{"href":"https:\/\/sustain-ed.eu\/es\/wp-json\/wp\/v2\/pages\/29508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sustain-ed.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sustain-ed.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sustain-ed.eu\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sustain-ed.eu\/es\/wp-json\/wp\/v2\/comments?post=29508"}],"version-history":[{"count":0,"href":"https:\/\/sustain-ed.eu\/es\/wp-json\/wp\/v2\/pages\/29508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sustain-ed.eu\/es\/wp-json\/wp\/v2\/media\/22040"}],"wp:attachment":[{"href":"https:\/\/sustain-ed.eu\/es\/wp-json\/wp\/v2\/media?parent=29508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}